    {"id":25953,"date":"2022-12-06T13:12:00","date_gmt":"2022-12-06T18:12:00","guid":{"rendered":"https:\/\/www.volarisgroup.com\/press-room\/a-marca-intellicene-e-lancada-apos-a-conclusao-da-aquisicao-pelo-volaris-group\/"},"modified":"2025-02-22T14:54:18","modified_gmt":"2025-02-22T19:54:18","slug":"a-marca-intellicene-e-lancada-apos-a-conclusao-da-aquisicao-pelo-volaris-group","status":"publish","type":"press-release","link":"https:\/\/www.volarisgroup.com\/pt-br\/press-room\/a-marca-intellicene-e-lancada-apos-a-conclusao-da-aquisicao-pelo-volaris-group\/","title":{"rendered":"A Marca Intellicene \u00e9 Lan\u00e7ada Ap\u00f3s a Conclus\u00e3o da Aquisi\u00e7\u00e3o pelo Volaris Group"},"content":{"rendered":"<p style=\"text-align: center;\"><em>A fornecedora global de tecnologia de seguran\u00e7a com mais de 20 anos de experi\u00eancia abra\u00e7a a pr\u00f3xima evolu\u00e7\u00e3o de seus neg\u00f3cios com uma marca renovada e uma lideran\u00e7a revigorada<\/em><\/p>\n<p><strong>MELVILLE, N.Y., 6 de dezembro de <\/strong><a href=\"https:\/\/intellicene.com\/intellicene-brand-launches-after-completion-of-acquisition-by-volaris-group\/\">2022<\/a><strong>&#8211; A Intellicene<\/strong>, fornecedora de plataformas de software inteligentes que capacitam as organiza\u00e7\u00f5es a entender melhor e responder a eventos de miss\u00e3o cr\u00edtica, anunciou hoje o fechamento de sua aquisi\u00e7\u00e3o pelo Volaris Group e o lan\u00e7amento de sua nova marca. Anteriormente conhecida como Cognyte Situational Intelligence Solutions (SIS), a nova Intellicene incorpora uma nova dire\u00e7\u00e3o estrat\u00e9gica e uma ambi\u00e7\u00e3o de ser a l\u00edder global de intelig\u00eancia de seguran\u00e7a preferida.<\/p>\n<p>Liderada pelo veterano executivo de seguran\u00e7a Alan Stoddard, a Intellicene incorpora antigos funcion\u00e1rios e ativos da SIS, incluindo o conjunto de tecnologias Symphia. O novo nome e o novo direcionamento estrat\u00e9gico tamb\u00e9m introduzem a &#8220;Era da Intelig\u00eancia&#8221;, que mostra a miss\u00e3o da Intellicene de transformar o gerenciamento de seguran\u00e7a de um esfor\u00e7o reativo em um processo proativo altamente eficaz, orientado por dados e mensur\u00e1vel.<\/p>\n<p>O lan\u00e7amento da Intellicene ocorre ap\u00f3s um ano incrivelmente bem-sucedido, no qual a empresa fortaleceu sua presen\u00e7a com a conquista de novos clientes. A filosofia de compra e manuten\u00e7\u00e3o da Volaris proporciona estabilidade, melhores pr\u00e1ticas compartilhadas e uma presen\u00e7a global que pode criar novas oportunidades para a Intellicene.<\/p>\n<p>Situada no nexo entre conscientiza\u00e7\u00e3o, percep\u00e7\u00e3o e a\u00e7\u00e3o, a Intellicene oferece plataformas de software integradas e inteligentes que ajudam os l\u00edderes a entender melhor e responder a situa\u00e7\u00f5es cr\u00edticas em suas organiza\u00e7\u00f5es. A empresa tem fornecido plataformas inteligentes de gerenciamento de seguran\u00e7a para uma ampla variedade de empresas globais de miss\u00e3o cr\u00edtica h\u00e1 mais de 20 anos, desde sua forma\u00e7\u00e3o sob a Verint Systems em 2002.<\/p>\n<p>&#8220;Estamos entusiasmados com a entrada da Intellicene no pr\u00f3ximo cap\u00edtulo e, juntamente com a Volaris, vemos oportunidades atraentes para acelerar nossa trajet\u00f3ria de crescimento e melhorar o foco no cliente&#8221;, disse o CEO Alan Stoddard. &#8220;Com o forte apoio de nossos novos propriet\u00e1rios, estamos bem posicionados para capitalizar as muitas oportunidades que temos pela frente e vemos um enorme potencial para expandir nosso alcance em novos mercados e impulsionar novas inova\u00e7\u00f5es e capacidades.&#8221;<\/p>\n<p>A Intellicene est\u00e1 focada em garantir que os stakeholders tenham as ferramentas certas para ajudar a proteger opera\u00e7\u00f5es, ativos e pessoas. Com ampla expertise nas \u00e1reas de seguran\u00e7a e TI, a empresa e sua equipe t\u00eam ajudado a garantir a seguran\u00e7a de marcas bem conceituadas, desenvolvendo solu\u00e7\u00f5es que ajudam os l\u00edderes a entender melhor e a responder a situa\u00e7\u00f5es cr\u00edticas. Sua plataforma de software Symphia se conecta e correlaciona dados de praticamente qualquer dispositivo, sistema ou software, fornecendo a conscientiza\u00e7\u00e3o em tempo real e os insights acion\u00e1veis necess\u00e1rios para identificar poss\u00edveis amea\u00e7as e responder de forma eficaz.<\/p>\n<p>&#8220;Temos o prazer de concluir esta aquisi\u00e7\u00e3o e apoiar Alan e a equipe de gest\u00e3o na constru\u00e7\u00e3o de sua vis\u00e3o para a Intellicene&#8221;, disse Carl Bruce, do Volaris Group. &#8220;Vemos esse mercado como uma tremenda oportunidade e, sob nossa propriedade, a Intellicene est\u00e1 bem posicionada para o crescimento futuro.&#8221;<\/p>\n<p>Stoddard traz uma experi\u00eancia significativa na lideran\u00e7a de organiza\u00e7\u00f5es globais e tem mais de 12 anos de experi\u00eancia no setor de seguran\u00e7a. Al\u00e9m de Stoddard, a equipe de lideran\u00e7a s\u00eanior inclui Uri Shaffer, vice-presidente de vendas para EMEA e APAC; Craig Levin, diretor financeiro; Yosi Rahamim, vice-presidente de pesquisa e desenvolvimento; Mike Howanitz, vice-presidente de vendas e opera\u00e7\u00f5es comerciais; Joey Caluori, vice-presidente de opera\u00e7\u00f5es; Eran Wachman, vice-presidente de gerenciamento de produtos; Tracy Markum, vice-presidente de vendas para as Am\u00e9ricas; e Jeffrey Lewis, diretor de marketing.<\/p>\n<p><strong>Sobre a Intellicene<\/strong><br \/>\nA Intellicene est\u00e1 na conex\u00e3o entre conscientiza\u00e7\u00e3o, insight e a\u00e7\u00e3o. Nossa miss\u00e3o \u00e9 ajudar as organiza\u00e7\u00f5es de todo o mundo a harmonizar a seguran\u00e7a, a continuidade dos neg\u00f3cios e o gerenciamento de riscos para proteger o que \u00e9 mais importante. Ao fornecer plataformas de software integradas e inteligentes que ajudam voc\u00ea a entender melhor e responder a eventos de miss\u00e3o cr\u00edtica, a Intellicene o capacita a gerenciar com efici\u00eancia as opera\u00e7\u00f5es de seguran\u00e7a e de neg\u00f3cios mais complexas. Desde aplicativos m\u00f3veis e an\u00e1lises orientadas por IA at\u00e9 software infinitamente escal\u00e1vel e dispositivos inteligentes, estamos criando tecnologia avan\u00e7ada que eleva o n\u00edvel e torna o mundo mais seguro. Para mais informa\u00e7\u00f5es, visite \u00a0<a href=\"http:\/\/www.intellicene.com\">www.intellicene.com.<\/a><\/p>\n<p><strong>Sobre o Volaris Group<\/strong><br \/>\nA Volaris adquire, fortalece e desenvolve empresas de tecnologia de mercados verticais. Como um grupo operacional da Constellation Software Inc., a Volaris tem como objetivo fortalecer as empresas nos mercados em que competem e permitir que elas cres\u00e7am, seja por meio de medidas org\u00e2nicas, como novas iniciativas e desenvolvimento de produtos, neg\u00f3cios di\u00e1rios ou aquisi\u00e7\u00f5es complementares. Saiba mais em \u00a0<a href=\"https:\/\/www.volarisgroup.com\" target=\"_blank\" rel=\"noopener\">www.volarisgroup.com.<\/a><\/p>\n<p><strong>Contato para m\u00eddia<\/strong><br \/>\nRyan Hill<br \/>\nVolaris Group<br \/>\nTel:<a href=\"tel:14168310305\">+1 416-831-0305<\/a><br \/>\n<a href=\"mailto:ryans.hill@volarisgroup.com\">ryans.hill@volarisgroup.com<\/a><\/p>\n","protected":false},"author":16,"featured_media":18446,"template":"","meta":{"_acf_changed":false,"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_analysis_target_kw":""},"tags":[],"pr-category":[710],"class_list":["post-25953","press-release","type-press-release","status-publish","has-post-thumbnail","hentry","pr-category-categoria-padrao"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.volarisgroup.com\/pt-br\/wp-json\/wp\/v2\/press-release\/25953","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.volarisgroup.com\/pt-br\/wp-json\/wp\/v2\/press-release"}],"about":[{"href":"https:\/\/www.volarisgroup.com\/pt-br\/wp-json\/wp\/v2\/types\/press-release"}],"author":[{"embeddable":true,"href":"https:\/\/www.volarisgroup.com\/pt-br\/wp-json\/wp\/v2\/users\/16"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.volarisgroup.com\/pt-br\/wp-json\/wp\/v2\/media\/18446"}],"wp:attachment":[{"href":"https:\/\/www.volarisgroup.com\/pt-br\/wp-json\/wp\/v2\/media?parent=25953"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.volarisgroup.com\/pt-br\/wp-json\/wp\/v2\/tags?post=25953"},{"taxonomy":"pr-category","embeddable":true,"href":"https:\/\/www.volarisgroup.com\/pt-br\/wp-json\/wp\/v2\/pr-category?post=25953"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}