{"id":25379,"date":"2023-04-24T10:38:00","date_gmt":"2023-04-24T14:38:00","guid":{"rendered":"https:\/\/www.volarisgroup.com\/acquired-knowledge\/de-meilleures-facons-davoir-des-conversations-difficiles\/"},"modified":"2024-12-19T07:48:51","modified_gmt":"2024-12-19T12:48:51","slug":"de-meilleures-facons-davoir-des-conversations-difficiles","status":"publish","type":"acquired-knowledge","link":"https:\/\/www.volarisgroup.com\/fr\/acquired-knowledge\/de-meilleures-facons-davoir-des-conversations-difficiles\/","title":{"rendered":"De meilleures fa\u00e7ons d&rsquo;avoir des conversations difficiles"},"content":{"rendered":"<p>Les conversations difficiles font partie de la vie professionnelle. Les gens sont souvent stress\u00e9s avant ces conversations, et le fait d&rsquo;\u00eatre confront\u00e9 \u00e0 un sujet \u00e9pineux peut aggraver une situation d\u00e9j\u00e0 difficile si la discussion est mal g\u00e9r\u00e9e. Heureusement, am\u00e9liorer votre capacit\u00e9 \u00e0 transformer ces interactions en opportunit\u00e9s productives est une comp\u00e9tence qui peut \u00eatre d\u00e9velopp\u00e9e. Bien que chaque situation soit unique, le processus de d\u00e9veloppement des talents de Volaris permet \u00e0 nos dirigeants de tirer le meilleur parti d&rsquo;un \u00e9change, m\u00eame inconfortable, en exposant le probl\u00e8me et en r\u00e9fl\u00e9chissant \u00e0 l&rsquo;issue souhait\u00e9e. <\/p>\n<h2>Dire \u00ab\u00a0non\u00a0\u00bb<\/h2>\n<p>Non. Un seul mot, mais il peut \u00eatre tr\u00e8s difficile de le dire lorsque la personne qui pose la question est en position de force par rapport \u00e0 vous, ou parce que vous aimeriez \u00eatre utile. Certaines personnes r\u00e9pondent par d\u00e9faut \u00ab\u00a0oui\u00a0\u00bb ou \u00ab\u00a0non\u00a0\u00bb, quelle que soit la question pos\u00e9e. Si vous r\u00e9pondez \u00ab\u00a0oui\u00a0\u00bb par d\u00e9faut parce que vous voulez \u00e9viter les conflits ou vous rendre utile, vous finirez par \u00eatre trop engag\u00e9. Si vous r\u00e9pondez \u00ab\u00a0non\u00a0\u00bb par d\u00e9faut pour rester dans votre zone de confort, vous risquez de manquer une nouvelle exp\u00e9rience que vous appr\u00e9ciez vraiment ou de vous priver d&rsquo;opportunit\u00e9s futures. Certaines personnes ne peuvent pas dire \u00ab\u00a0non\u00a0\u00bb parce qu&rsquo;elles s&rsquo;inqui\u00e8tent de ce que cela signifie pour la personne qui pose la question, mais il existe de nombreuses fa\u00e7ons d&rsquo;\u00eatre utile tout en refusant une demande : <\/p>\n<ul>\n<li><strong>Les demandes de temps :<\/strong> Vous pouvez peut-\u00eatre orienter la personne vers des ressources gratuites ou fixer une limite au temps que vous pouvez consacrer \u00e0 une demande sp\u00e9cifique. Si vous \u00eates un expert en la mati\u00e8re, envisagez de cr\u00e9er une FAQ ou d&rsquo;autres documents que vous pourrez partager librement en cas de besoin. <\/li>\n<li><strong>Interruptions\/questions : <\/strong>La premi\u00e8re \u00e9tape consiste \u00e0 \u00e9valuer les priorit\u00e9s. Vous n&rsquo;en serez peut-\u00eatre pas ravi, mais il se peut que vous deviez changer d&rsquo;avis. Si la question n&rsquo;est pas prioritaire pour vous, mais qu&rsquo;elle l&rsquo;est pour eux, \u00e9valuez si un petit effort de votre part peut leur permettre de continuer \u00e0 avancer. Si vous devez dire \u00ab\u00a0non\u00a0\u00bb cat\u00e9goriquement, faites-le en expliquant pourquoi et proposez des options si vous en connaissez.   <\/li>\n<li><strong>\u00ab\u00a0Ce n&rsquo;est pas mon travail\u00a0\u00bb : <\/strong>Cette question peut \u00eatre source de conflit si elle est mal trait\u00e9e. Dans certains cas, la personne qui pose la question ignore r\u00e9ellement que ce n&rsquo;est pas votre travail &#8211; vous \u00eates peut-\u00eatre la seule personne qu&rsquo;elle connaisse qui puisse le savoir. Expliquer en quoi consiste votre travail peut donner un contexte et, une fois encore, si vous pouvez rediriger la personne vers la bonne \u00e9quipe ou la bonne personne, c&rsquo;est utile. Par ailleurs, lorsque vous \u00eates un peu \u00e9puis\u00e9, votre d\u00e9finition de \u00ab\u00a0votre travail\u00a0\u00bb se r\u00e9tr\u00e9cit et votre r\u00e9ponse spontan\u00e9e aux demandes sera une forme de \u00ab\u00a0non\u00a0\u00bb. Envisagez d&rsquo;\u00eatre un peu transparent sur votre situation (\u00ab\u00a0Je suis un peu stress\u00e9 en ce moment\u00a0\u00bb) et proposez de faire un suivi dans quelques jours si cela fonctionne.    <\/li>\n<li><strong>Travail suppl\u00e9mentaire :<\/strong> Si votre sup\u00e9rieur vous demande d&rsquo;effectuer un travail suppl\u00e9mentaire ou de prendre en charge un nouveau projet, il doit probablement r\u00e9pondre par l&rsquo;affirmative, mais ne supposez pas qu&rsquo;il conna\u00eet exactement vos priorit\u00e9s actuelles ou les conflits potentiels. Discutez de votre charge de travail et d\u00e9finissez vos attentes en mati\u00e8re de d\u00e9lais et de priorit\u00e9s. S&rsquo;il y a des indications que votre r\u00f4le professionnel \u00e9volue vers quelque chose de nouveau, une ren\u00e9gociation peut s&rsquo;av\u00e9rer n\u00e9cessaire. Dans l&rsquo;ensemble, faire preuve d&rsquo;\u00e9l\u00e9gance signifie continuer \u00e0 soutenir l&rsquo;ensemble du travail tout en \u00e9tablissant des priorit\u00e9s claires.   <\/li>\n<li><strong>Recruteurs ou offres d&#8217;emploi :<\/strong> Un \u00ab\u00a0non\u00a0\u00bb ferme dans ce cas peut signifier qu&rsquo;il faut parler avec eux pour savoir ce qu&rsquo;ils recherchent &#8211; \u00e9ventuellement, vous pouvez proposer de partager l&rsquo;opportunit\u00e9 avec votre r\u00e9seau.<\/li>\n<li><strong>On vous demande de vous recommander \u00e0 d&rsquo;autres personnes :<\/strong> Si vous \u00eates heureux \u00e0 100 % de donner une recommandation, il n&rsquo;y a pas de probl\u00e8me. Mais il arrive que l&rsquo;on vous demande de le faire alors que vous avez des r\u00e9serves \u00e0 ce sujet, ou que votre r\u00e9ponse, si elle est honn\u00eate, ne soit pas tout \u00e0 fait favorable. Il n&rsquo;y a pas de mal \u00e0 donner une r\u00e9ponse diplomatique, comme \u00ab\u00a0Je ne pense pas \u00eatre la bonne personne pour recommander ce projet\u00a0\u00bb, ou \u00e0 dire o\u00f9 sont les limites, comme \u00ab\u00a0Je peux parler de ce projet, mais je ne recommanderai aucun autre de vos travaux\u00a0\u00bb. Parfois, cela permet d&rsquo;\u00e9viter un \u00ab\u00a0non\u00a0\u00bb cat\u00e9gorique.   <\/li>\n<\/ul>\n<h2>Le travail pr\u00e9paratoire \u00e0 une conversation difficile<\/h2>\n<p>Si l&rsquo;on en croit le nombre d&rsquo;ouvrages consacr\u00e9s aux conversations difficiles, c&rsquo;est un sujet qui pr\u00e9occupe de nombreuses personnes. Il s&rsquo;agit par exemple d&rsquo;\u00e9valuer les employ\u00e9s peu performants, de licencier quelqu&rsquo;un, de faire en sorte que des parties prenantes en conflit parviennent \u00e0 un accord ou de donner un retour d&rsquo;information critique \u00e0 quelqu&rsquo;un. Comme le souligne l&rsquo;auteur \u00e0 succ\u00e8s <a href=\"https:\/\/hbr.org\/2019\/01\/4-things-to-do-before-a-tough-conversation\" target=\"_blank\" rel=\"noopener\">Joseph Grenny<\/a>, la pr\u00e9paration a un impact important sur la r\u00e9ussite de la conversation : <\/p>\n<h3>1. Adoptez le bon \u00e9tat d&rsquo;esprit<\/h3>\n<p>Vous pouvez \u00eatre \u00e0 l&rsquo;origine d&rsquo;une conversation difficile. Un adage dit : \u00ab\u00a0Si vous cherchez la bagarre, vous en trouverez une\u00a0\u00bb. En revanche, si vous entamez une conversation en pensant que, quoi qu&rsquo;il arrive, il en sortira quelque chose de positif, vous obtiendrez de meilleurs r\u00e9sultats. Il s&rsquo;agit \u00e9galement de comprendre ce que l&rsquo;autre personne sait et d&rsquo;o\u00f9 elle vient. Dispose-t-il des m\u00eames informations que vous ? Per\u00e7oit-il les m\u00eames probl\u00e8mes que vous ? A-t-il des motivations diff\u00e9rentes des v\u00f4tres ? Le fait de comprendre sa position peut vous aider \u00e0 recadrer la conversation et peut-\u00eatre \u00e0 red\u00e9finir votre relation pour en faire des partenaires plut\u00f4t que des adversaires. L&#8217;empathie peut \u00eatre tr\u00e8s utile.  <\/p>\n<h3>2. V\u00e9rifiez vos motivations<\/h3>\n<p>Lorsque vous \u00eates stress\u00e9 ou menac\u00e9, vos motivations peuvent devenir \u00e9go\u00efstes et \u00e0 court terme. Les gens s&rsquo;inqui\u00e8tent de savoir si les autres les aimeront, de leur r\u00e9putation, d&rsquo;avoir raison, de gagner, ou ils veulent simplement \u00e9viter les conflits. Cela est vrai quel que soit le niveau hi\u00e9rarchique de l&rsquo;organisation. Posez-vous la question : Qu&rsquo;est-ce que je veux vraiment pour moi ? Pour l&rsquo;autre personne ? Pour les autres parties prenantes ? Les r\u00e9ponses doivent correspondre \u00e0 des r\u00e9sultats positifs et \u00e0 votre \u00e9thique. Elles vous aideront \u00e0 vous concentrer et \u00e0 rester calme. \u00cates-vous conscient de vos objectifs cach\u00e9s ? Vous pensez peut-\u00eatre avoir des objectifs honorables, mais si vous vous laissez aller \u00e0 des critiques excessives, vous risquez de r\u00e9v\u00e9ler quelque chose sur vos motivations &#8211; par exemple, gagner ou punir au lieu de parvenir \u00e0 un bon r\u00e9sultat.  <\/p>\n<h3>3. G\u00e9rez vos \u00e9motions<\/h3>\n<p>Les \u00e9motions n\u00e9gatives sont un obstacle \u00e0 une conversation productive. En cas de stress, vos \u00e9motions imm\u00e9diates peuvent \u00eatre la col\u00e8re, la peur et l&rsquo;attitude d\u00e9fensive. Comme le dit Grenny, \u00ab\u00a0nos \u00e9motions ont moins \u00e0 voir avec ce que fait l&rsquo;autre personne qu&rsquo;avec l&rsquo;histoire que nous nous racontons \u00e0 propos de ce qu&rsquo;elle fait\u00a0\u00bb. Il est facile de construire une histoire avec un m\u00e9chant (eux) et une victime (nous). En modifiant les r\u00f4les pour qu&rsquo;ils correspondent \u00e0 ceux des acteurs d&rsquo;une histoire, vous pouvez voir comment vous avez contribu\u00e9 \u00e0 la dynamique ou \u00e0 la situation actuelle. Cela permet d&rsquo;\u00e9liminer les \u00e9motions. En r\u00e9fl\u00e9chissant \u00e0 votre r\u00e9action \u00e9motionnelle imm\u00e9diate, vous pourriez d\u00e9couvrir des raisons plus profondes pour lesquelles vous \u00eates si contrari\u00e9 par la situation.   <\/p>\n<h3>4. Rassembler les faits<\/h3>\n<p>Par nature, une conversation difficile donnera lieu \u00e0 des points de vue oppos\u00e9s. Il est pr\u00e9f\u00e9rable de commencer par les faits dont vous disposez plut\u00f4t que de pr\u00e9senter une conclusion. Sinon, il s&rsquo;agit d&rsquo;un concours et non d&rsquo;une conversation. La capacit\u00e9 \u00e0 donner un feedback critique clair et sp\u00e9cifique tout en restant \u00e9motionnellement neutre (ou m\u00eame \u00ab\u00a0chaleureux\u00a0\u00bb) est une comp\u00e9tence qui doit \u00eatre d\u00e9velopp\u00e9e. Parler de l&rsquo;impact et des r\u00e9sultats d&rsquo;un mauvais comportement ou d&rsquo;une performance insuffisante peut \u00e9galement aider \u00e0 orienter la discussion en dehors des opinions personnelles. Parfois, une personne sait qu&rsquo;elle ne travaille pas bien, mais elle s&rsquo;accroche par peur (peur de perdre son emploi, peur de demander de l&rsquo;aide, honte de son comportement pass\u00e9) et perd de vue qu&rsquo;elle emp\u00eache d&rsquo;autres personnes de bien faire leur travail. Le fait de parler ouvertement des effets n\u00e9gatifs peut les aider \u00e0 comprendre pourquoi les choses doivent changer. Bien entendu, les faits peuvent \u00eatre contest\u00e9s et fauss\u00e9s, et vous devez donc laisser \u00e0 l&rsquo;autre personne la possibilit\u00e9 de s&rsquo;exprimer sur les faits tels que vous les pr\u00e9sentez. Dans le cas d&rsquo;une d\u00e9cision d\u00e9j\u00e0 prise, cela ne changera pas le r\u00e9sultat. N\u00e9anmoins, toutes les parties auront le sentiment d&rsquo;\u00eatre entendues.   <\/p>\n<h3>5. Soyez curieux<\/h3>\n<p>Vous devez \u00eatre s\u00fbr de ce que vous devez dire\/accomplir, mais \u00eatre ouvert \u00e0 l&rsquo;id\u00e9e d&rsquo;apprendre quelque chose au cours de la conversation qui pourrait influencer votre point de vue. Faites-vous des suppositions sur les intentions de quelqu&rsquo;un d&rsquo;autre ? L&rsquo;\u00e9coute active peut aider les deux parties \u00e0 surmonter une conversation difficile. Comme l&rsquo;a dit le c\u00e9l\u00e8bre diplomate Dean Rusk, \u00ab\u00a0lorsque vous \u00e9coutez profond\u00e9ment et sinc\u00e8rement, les autres ressentent moins le besoin de vous r\u00e9sister pour se faire entendre\u00a0\u00bb. <\/p>\n<h2>La fa\u00e7on dont vous dites les choses a de l&rsquo;importance<\/h2>\n<p>Une mauvaise tournure de phrase peut faire \u00e9chouer toutes les bonnes intentions. Lorsque vous planifiez ce que vous allez dire, vous devez tenir compte du fait que vous conversez avec un autre \u00eatre humain, qui aura lui aussi des sentiments et des opinions. Certaines phrases d\u00e9clenchent une r\u00e9action n\u00e9gative imm\u00e9diate. Elles semblent \u00e9videntes, mais il est surprenant de constater \u00e0 quel point les gens les utilisent souvent, d&rsquo;autant plus qu&rsquo;ils s&rsquo;en offusqueraient probablement s&rsquo;ils se trouvaient \u00e0 l&rsquo;autre bout du fil. Les d\u00e9clencheurs peuvent \u00e9galement \u00eatre personnels et li\u00e9s \u00e0 l&rsquo;exp\u00e9rience v\u00e9cue d&rsquo;une personne (dont vous ne savez rien). Dans un <a href=\"https:\/\/hbr.org\/2021\/06\/words-and-phrases-to-avoid-in-a-difficult-conversation\" target=\"_blank\" rel=\"noopener\">article<\/a> publi\u00e9 dans la Harvard Business Review, James R. Detert, universitaire de renom, s&rsquo;est pench\u00e9 sur les phrases d\u00e9clencheuses en se basant sur les erreurs les plus courantes. Voici ses conseils : <\/p>\n<ul>\n<li><strong>Ne partez pas du principe que votre point de vue est \u00e9vident.<\/strong> D\u00e9clenchez des phrases comme \u00a0\u00bb <em>\u00e9videmment\u00a0\u00bb, \u00ab\u00a0clairement\u00a0\u00bb, \u00ab\u00a0sans aucun doute\u00a0\u00bb, comme nous le savons tous. <\/em>Elles alimentent un r\u00e9alisme na\u00eff, dans lequel vous croyez avoir acc\u00e8s \u00e0 une r\u00e9alit\u00e9 objective que tout le monde verra et approuvera, ou une arrogance, dans laquelle vous supposez que tout autre point de vue est sans importance.<\/li>\n<li><strong>N&rsquo;exag\u00e9rez pas.<\/strong> D\u00e9clenchez des phrases comme <em>toujours, jamais.<\/em> Les d\u00e9clarations exag\u00e9r\u00e9es ressemblent souvent \u00e0 des accusations lorsqu&rsquo;elles d\u00e9crivent un comportement n\u00e9gatif. Elles peuvent saper votre cr\u00e9dibilit\u00e9 et conduire \u00e0 un d\u00e9bat sur la fr\u00e9quence ou la v\u00e9rit\u00e9 plut\u00f4t que sur le comportement et les r\u00e9sultats. Si votre intention est d&rsquo;amener quelqu&rsquo;un \u00e0 commencer ou \u00e0 arr\u00eater de faire quelque chose, restez concentr\u00e9 sur ce point.  <\/li>\n<li><strong>Ne leur dites pas ce qu&rsquo;ils doivent faire (surtout si vous n&rsquo;\u00eates pas leur patron).<\/strong> D\u00e9clenchez des phrases telles que <em>vous devriez faire ceci, ce n&rsquo;est pas comme \u00e7a qu&rsquo;il faut faire.<\/em> Si vous essayez d&rsquo;influencer un comportement, il est pr\u00e9f\u00e9rable de laisser la personne d\u00e9cider pour elle-m\u00eame. Cela ne veut pas dire que vous ne pouvez pas influencer cette d\u00e9cision, mais il est plus convaincant de discuter des options et des donn\u00e9es. <\/li>\n<li><strong>Ne mettez pas en doute le caract\u00e8re ou l&rsquo;int\u00e9grit\u00e9 de quelqu&rsquo;un.<\/strong> D\u00e9clenchez des phrases comme \u00a0\u00bb <em>non professionnel\u00a0\u00bb, \u00ab\u00a0faux\u00a0\u00bb, \u00ab\u00a0contraire \u00e0 l&rsquo;\u00e9thique\u00a0\u00bb.<\/em> Ces choses peuvent \u00eatre vraies, mais surtout si ce n&rsquo;est pas votre responsabilit\u00e9 de les mettre en \u00e9vidence, vous mettrez imm\u00e9diatement fin \u00e0 la conversation. En posant la question \u00ab\u00a0pourquoi ?\u00a0\u00bb, vous pouvez obtenir de nouvelles informations sur ce qui s&rsquo;est pass\u00e9. S&rsquo;en tenir aux r\u00e9sultats et aux comportements observables est pr\u00e9f\u00e9rable \u00e0 ce qui s&rsquo;apparente \u00e0 une attaque personnelle.  <\/li>\n<li><strong>Ne dites pas : \u00ab\u00a0Ce n&rsquo;est pas personnel<\/strong>\u00ab\u00a0. D\u00e8s que vous le dites, cela devient personnel. Si une personne est clairement affect\u00e9e par quelque chose que vous avez dit ou fait, cela ne fera qu&rsquo;aggraver la situation. Au lieu de cela, vous pouvez reconna\u00eetre que c&rsquo;est personnel pour eux, m\u00eame si ce n&rsquo;est pas le cas pour vous.  <\/li>\n<\/ul>\n<p>Chacun a ses propres d\u00e9clencheurs qui peuvent faire d\u00e9railler une conversation difficile, et il est important de reconna\u00eetre que personne n&rsquo;a toujours raison. Mais si vous devez avoir une conversation difficile, prendre le temps de r\u00e9fl\u00e9chir \u00e0 votre approche et \u00e0 votre message peut vous aider \u00e0 \u00e9viter des conflits inutiles. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les conversations difficiles font partie de la vie professionnelle. Les gens sont souvent stress\u00e9s avant ces conversations, et le fait d&rsquo;\u00eatre confront\u00e9 \u00e0 un sujet \u00e9pineux peut aggraver une situation d\u00e9j\u00e0 difficile si la discussion est mal g\u00e9r\u00e9e. Heureusement, am\u00e9liorer votre capacit\u00e9 \u00e0 transformer ces interactions en opportunit\u00e9s productives est une comp\u00e9tence qui peut \u00eatre &#8230; <a title=\"De meilleures fa\u00e7ons d&rsquo;avoir des conversations difficiles\" class=\"read-more\" href=\"https:\/\/www.volarisgroup.com\/fr\/acquired-knowledge\/de-meilleures-facons-davoir-des-conversations-difficiles\/\" aria-label=\"En savoir plus sur De meilleures fa\u00e7ons d&rsquo;avoir des conversations difficiles\">Lire la suite<\/a><\/p>\n","protected":false},"author":9,"featured_media":50398,"menu_order":0,"template":"","format":"standard","meta":{"_acf_changed":false,"_seopress_titles_title":"De meilleures fa\u00e7ons d'avoir des conversations difficiles","_seopress_titles_desc":"Les conversations difficiles font partie de la vie professionnelle, mais am\u00e9liorer votre capacit\u00e9 \u00e0 transformer ces interactions en opportunit\u00e9s productives est une comp\u00e9tence qui peut \u00eatre d\u00e9velopp\u00e9e.","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"both","_seopress_redirections_param":"","_seopress_redirections_type":301,"_seopress_analysis_target_kw":"","_seopress_news_disabled":"","_seopress_video_disabled":"","_seopress_video":[],"_seopress_pro_schemas_manual":[],"_seopress_pro_rich_snippets_disable_all":"","_seopress_pro_rich_snippets_disable":[],"_seopress_pro_schemas":[],"footnotes":""},"tags":[888],"ak-category":[708],"language-category":[],"class_list":["post-25379","acquired-knowledge","type-acquired-knowledge","status-publish","format-standard","has-post-thumbnail","hentry","tag-conseils-en-matiere-de-leadership","ak-category-renforcer"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.volarisgroup.com\/fr\/wp-json\/wp\/v2\/acquired-knowledge\/25379","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.volarisgroup.com\/fr\/wp-json\/wp\/v2\/acquired-knowledge"}],"about":[{"href":"https:\/\/www.volarisgroup.com\/fr\/wp-json\/wp\/v2\/types\/acquired-knowledge"}],"author":[{"embeddable":true,"href":"https:\/\/www.volarisgroup.com\/fr\/wp-json\/wp\/v2\/users\/9"}],"version-history":[{"count":2,"href":"https:\/\/www.volarisgroup.com\/fr\/wp-json\/wp\/v2\/acquired-knowledge\/25379\/revisions"}],"predecessor-version":[{"id":34541,"href":"https:\/\/www.volarisgroup.com\/fr\/wp-json\/wp\/v2\/acquired-knowledge\/25379\/revisions\/34541"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.volarisgroup.com\/fr\/wp-json\/wp\/v2\/media\/50398"}],"wp:attachment":[{"href":"https:\/\/www.volarisgroup.com\/fr\/wp-json\/wp\/v2\/media?parent=25379"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.volarisgroup.com\/fr\/wp-json\/wp\/v2\/tags?post=25379"},{"taxonomy":"ak-category","embeddable":true,"href":"https:\/\/www.volarisgroup.com\/fr\/wp-json\/wp\/v2\/ak-category?post=25379"},{"taxonomy":"language-category","embeddable":true,"href":"https:\/\/www.volarisgroup.com\/fr\/wp-json\/wp\/v2\/language-category?post=25379"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}